{"id":10800,"date":"2026-02-14T06:24:42","date_gmt":"2026-02-14T11:24:42","guid":{"rendered":"https:\/\/kimmelpsychology.com\/recordando-a-stoneman-douglas-ocho-anos-despues\/"},"modified":"2026-02-14T06:35:22","modified_gmt":"2026-02-14T11:35:22","slug":"recordando-a-stoneman-douglas-ocho-anos-despues","status":"publish","type":"post","link":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/","title":{"rendered":"Recordando a Stoneman Douglas&#8230; \u00a1Ocho a\u00f1os despu\u00e9s!"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Un Bolet\u00edn Electr\u00f3nico de Salud Mental de Joel I. Kimmel, Ph.D., P.A. &amp; Associates Volumen 20, N\u00famero 2<\/p>\n<p>Hoy se cumple el octavo aniversario de la tragedia del instituto Marjory Stoneman Douglas.<\/p>\n<p>Mientras hacemos una pausa para recordar las diecisiete vidas perdidas, comparto una reflexi\u00f3n editada y escrita seis d\u00edas despu\u00e9s del tiroteo. Aunque la vida en Parkland ha avanzado significativamente y se han aprendido lecciones importantes, los aniversarios a menudo despiertan emociones y recuerdos intensos. Tomarse un tiempo para reflexionar honra a quienes perdieron la vida y contribuye a que nuestra comunidad siga sanando.  <\/p>\n<p><strong>Escrito originalmente el 20 de febrero de 2018<\/strong><\/p>\n<p>He ejercido como psic\u00f3loga en esta comunidad durante m\u00e1s de cuarenta a\u00f1os. Durante ese tiempo, he trabajado con miles de personas que se enfrentan a una amplia gama de retos. Mi experiencia ha incluido programas de rehabilitaci\u00f3n de drogadictos, equipos de protecci\u00f3n de menores, intervenci\u00f3n en crisis y apoyo a v\u00edctimas de robos y muertes s\u00fabitas en el lugar de trabajo.  <\/p>\n<p>Sin embargo, nada ha sido tan profundamente perturbador para las personas y para esta comunidad como el tiroteo del instituto Marjory Stoneman Douglas. Esta tragedia es profundamente personal, no s\u00f3lo para m\u00ed, sino para todos los que viven, trabajan, crecieron aqu\u00ed o est\u00e1n relacionados con alguien que lo hace. <\/p>\n<p>Acontecimientos de esta magnitud desbordan nuestras capacidades habituales de afrontamiento. Perforan nuestra sensaci\u00f3n de seguridad y estabilidad. A su paso, podemos sentirnos impotentes, asustados, enfadados, insensibles o incr\u00e9dulos. Luchamos por dar sentido a algo que parece no tenerlo.   <\/p>\n<p>En una comunidad tan unida como la nuestra, todo el mundo se ve afectado de alguna manera. Compartimos las mismas escuelas, parques, restaurantes, lugares de culto y barrios. Lo que ocurri\u00f3 aqu\u00ed repercuti\u00f3 en todos los rincones de nuestra ciudad.  <\/p>\n<p>A los j\u00f3venes les quedaron recuerdos traum\u00e1ticos de aquel d\u00eda de San Valent\u00edn. Recuerdos que ning\u00fan adolescente deber\u00eda tener que cargar. Muchos sent\u00edan rabia por no haber sido protegidos, rabia por no haber visto las se\u00f1ales de advertencia, rabia por los fallos del sistema y rabia por cuestiones m\u00e1s amplias relacionadas con la seguridad y la salud mental.  <\/p>\n<p>Los padres y las familias cargaron con su propio dolor e indignaci\u00f3n. Confiaron en la sociedad para que protegiera a sus hijos, y esa confianza se tambale\u00f3. La pregunta \u00ab\u00bfC\u00f3mo ha podido ocurrir esto aqu\u00ed?\u00bb reson\u00f3 en toda la comunidad.  <\/p>\n<p>Curarse de un trauma lleva tiempo. Una \u00abnueva normalidad\u00bb no surge de la noche a la ma\u00f1ana, y la vida no puede simplemente volver a ser lo que era. Debe producirse un cambio significativo. Honrar las diecisiete vidas perdidas puede implicar la defensa de sus derechos, el compromiso con la comunidad, el apoyo a causas importantes para ellos o la b\u00fasqueda de formas personales de llevar adelante sus valores.   <\/p>\n<p>Desde una perspectiva psicol\u00f3gica, la recuperaci\u00f3n del trauma requiere restablecer la sensaci\u00f3n de seguridad, expresar la ira de forma constructiva y reconstruir rutinas que proporcionen estructura y previsibilidad. Los sentimientos de culpa, depresi\u00f3n, ansiedad y dolor son frecuentes y, cuando son necesarios, se abordan mejor con el apoyo de un profesional de la salud mental capacitado. <\/p>\n<p>Para los padres, varias acciones pueden ser especialmente \u00fatiles:<\/p>\n<ul>\n<li>Habla con tus hijos, y escucha incluso m\u00e1s de lo que hablas.<\/li>\n<li>Tranquil\u00edzales dici\u00e9ndoles que su casa sigue siendo un lugar seguro.<\/li>\n<li>Vigila los cambios en el sue\u00f1o, el apetito, el humor, el rendimiento escolar o el comportamiento.<\/li>\n<li>Limita la exposici\u00f3n repetida a las noticias y a la cobertura de los medios sociales, que pueden intensificar la angustia.<\/li>\n<li>S\u00e9 paciente contigo mismo y con los dem\u00e1s.<\/li>\n<li>Reconoce que los ni\u00f1os observan c\u00f3mo afrontan la situaci\u00f3n los adultos; tus respuestas son un modelo de resiliencia y regulaci\u00f3n.<\/li>\n<\/ul>\n<p>Con tiempo, apoyo y conexi\u00f3n con la comunidad, se produce la curaci\u00f3n. Estos acontecimientos nos cambian, pero el cambio tambi\u00e9n puede traer crecimiento. Cuando las comunidades se unen con compasi\u00f3n, respeto y cuidado mutuo, a menudo salen fortalecidas.  <\/p>\n<p>Nadie de los aqu\u00ed presentes qued\u00f3 indemne de esta tragedia. Sin embargo, juntos podemos seguir construyendo una comunidad definida no s\u00f3lo por lo que ocurri\u00f3, sino por c\u00f3mo respondimos con empat\u00eda, valent\u00eda y compromiso mutuo. <\/p>\n<p><strong>Actualiza<\/strong><\/p>\n<p>El tiempo cura, aunque los recuerdos sigan vivos. Muchos estudiantes de Douglas se han graduado en la universidad y han seguido adelante con vidas significativas. Aunque se ha avanzado mucho, el recuerdo sigue siendo esencial. Como escribi\u00f3 George Santayana: \u00ab<em>Los que no pueden recordar el pasado est\u00e1n condenados a repetirlo\u00bb.<\/em>   <\/p>\n<p>Que en este aniversario honremos las vidas perdidas recordando, apoy\u00e1ndonos unos a otros y continuando la labor de construir una comunidad m\u00e1s segura y compasiva.<\/p>\n<p>Hasta marzo&#8230;<\/p>\n<hr style=\"margin: 20px 0;\">\n<p style=\"font-size: 0.9em; color: #555;\">La informaci\u00f3n proporcionada en este bolet\u00edn electr\u00f3nico no sustituye al tratamiento profesional. Son las opiniones de los redactores y se facilitan \u00fanicamente con fines educativos.  Para la atenci\u00f3n a la salud mental, busca un profesional cualificado.<\/p>\n<p><small>  Si esta informaci\u00f3n te resulta \u00fatil, no dudes en compartirla con los dem\u00e1s.<\/small><\/p>\n<p style=\"font-size: 0.85em; color: #888; text-align: center;\">2025 Doctor Joel I. Kimmel, P.A. y Asociados<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un Bolet\u00edn Electr\u00f3nico de Salud Mental de Joel I. Kimmel, Ph.D., P.A. &amp; Associates Volumen 20, N\u00famero 2 Hoy se cumple el octavo aniversario de la tragedia del instituto Marjory Stoneman Douglas. Mientras hacemos una pausa para recordar las diecisiete vidas perdidas, comparto una reflexi\u00f3n editada y escrita seis d\u00edas despu\u00e9s del tiroteo. Aunque [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10801,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[367,368,244,215,245,226],"class_list":["post-10800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-aniversario-del-tiroteo-en-una-escuela","tag-apoyo-a-los-padres","tag-parkland-es","tag-sanacion","tag-stoneman-douglas-es","tag-trauma-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recordando a Stoneman Douglas 8 a\u00f1os despu\u00e9s<\/title>\n<meta name=\"description\" content=\"Una reflexi\u00f3n sobre el aniversario de Stoneman Douglas, la recuperaci\u00f3n del trauma y c\u00f3mo las familias y las comunidades siguen sanando en Parkland.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recordando a Stoneman Douglas 8 a\u00f1os despu\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Una reflexi\u00f3n sobre el aniversario de Stoneman Douglas, la recuperaci\u00f3n del trauma y c\u00f3mo las familias y las comunidades siguen sanando en Parkland.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/\" \/>\n<meta property=\"og:site_name\" content=\"Kimmel Psychology\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/KimmelPsychology\" \/>\n<meta property=\"article:author\" content=\"www. facebook.com\/Kimmelpsychology\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-14T11:24:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-14T11:35:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2026\/02\/Candles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"201\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DrJoel\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DrJoel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/\"},\"author\":{\"name\":\"DrJoel\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\"},\"headline\":\"Recordando a Stoneman Douglas&#8230; \u00a1Ocho a\u00f1os despu\u00e9s!\",\"datePublished\":\"2026-02-14T11:24:42+00:00\",\"dateModified\":\"2026-02-14T11:35:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/\"},\"wordCount\":887,\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2026\\/02\\/Candles.jpg\",\"keywords\":[\"aniversario del tiroteo en una escuela\",\"apoyo a los padres\",\"Parkland\",\"sanaci\u00f3n\",\"Stoneman Douglas\",\"trauma\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/\",\"name\":\"Recordando a Stoneman Douglas 8 a\u00f1os despu\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2026\\/02\\/Candles.jpg\",\"datePublished\":\"2026-02-14T11:24:42+00:00\",\"dateModified\":\"2026-02-14T11:35:22+00:00\",\"description\":\"Una reflexi\u00f3n sobre el aniversario de Stoneman Douglas, la recuperaci\u00f3n del trauma y c\u00f3mo las familias y las comunidades siguen sanando en Parkland.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/#primaryimage\",\"url\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2026\\/02\\/Candles.jpg\",\"contentUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2026\\/02\\/Candles.jpg\",\"width\":300,\"height\":201,\"caption\":\"Aniversario del tiroteo de Stoneman Douglas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/recordando-a-stoneman-douglas-ocho-anos-despues\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/kimmelhogar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recordando a Stoneman Douglas&#8230; \u00a1Ocho a\u00f1os despu\u00e9s!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"name\":\"Kimmel Psychology\",\"description\":\"Providing Psychological Services for Over 45 Years\",\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\",\"name\":\"KimmelPsychology\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"contentUrl\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"width\":682,\"height\":178,\"caption\":\"KimmelPsychology\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/KimmelPsychology\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\",\"name\":\"DrJoel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"caption\":\"DrJoel\"},\"sameAs\":[\"https:\\\/\\\/kimmelpsychology.com\",\"www. facebook.com\\\/Kimmelpsychology\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recordando a Stoneman Douglas 8 a\u00f1os despu\u00e9s","description":"Una reflexi\u00f3n sobre el aniversario de Stoneman Douglas, la recuperaci\u00f3n del trauma y c\u00f3mo las familias y las comunidades siguen sanando en Parkland.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/","og_locale":"es_ES","og_type":"article","og_title":"Recordando a Stoneman Douglas 8 a\u00f1os despu\u00e9s","og_description":"Una reflexi\u00f3n sobre el aniversario de Stoneman Douglas, la recuperaci\u00f3n del trauma y c\u00f3mo las familias y las comunidades siguen sanando en Parkland.","og_url":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/","og_site_name":"Kimmel Psychology","article_publisher":"http:\/\/www.facebook.com\/KimmelPsychology","article_author":"www. facebook.com\/Kimmelpsychology","article_published_time":"2026-02-14T11:24:42+00:00","article_modified_time":"2026-02-14T11:35:22+00:00","og_image":[{"width":300,"height":201,"url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2026\/02\/Candles.jpg","type":"image\/jpeg"}],"author":"DrJoel","twitter_misc":{"Escrito por":"DrJoel","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/#article","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/"},"author":{"name":"DrJoel","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a"},"headline":"Recordando a Stoneman Douglas&#8230; \u00a1Ocho a\u00f1os despu\u00e9s!","datePublished":"2026-02-14T11:24:42+00:00","dateModified":"2026-02-14T11:35:22+00:00","mainEntityOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/"},"wordCount":887,"publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2026\/02\/Candles.jpg","keywords":["aniversario del tiroteo en una escuela","apoyo a los padres","Parkland","sanaci\u00f3n","Stoneman Douglas","trauma"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/","url":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/","name":"Recordando a Stoneman Douglas 8 a\u00f1os despu\u00e9s","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/#primaryimage"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2026\/02\/Candles.jpg","datePublished":"2026-02-14T11:24:42+00:00","dateModified":"2026-02-14T11:35:22+00:00","description":"Una reflexi\u00f3n sobre el aniversario de Stoneman Douglas, la recuperaci\u00f3n del trauma y c\u00f3mo las familias y las comunidades siguen sanando en Parkland.","breadcrumb":{"@id":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/#primaryimage","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2026\/02\/Candles.jpg","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2026\/02\/Candles.jpg","width":300,"height":201,"caption":"Aniversario del tiroteo de Stoneman Douglas"},{"@type":"BreadcrumbList","@id":"https:\/\/kimmelpsychology.com\/es\/recordando-a-stoneman-douglas-ocho-anos-despues\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kimmelpsychology.com\/es\/kimmelhogar\/"},{"@type":"ListItem","position":2,"name":"Recordando a Stoneman Douglas&#8230; \u00a1Ocho a\u00f1os despu\u00e9s!"}]},{"@type":"WebSite","@id":"https:\/\/kimmelpsychology.com\/es\/#website","url":"https:\/\/kimmelpsychology.com\/es\/","name":"Kimmel Psychology","description":"Providing Psychological Services for Over 45 Years","publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimmelpsychology.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kimmelpsychology.com\/es\/#organization","name":"KimmelPsychology","url":"https:\/\/kimmelpsychology.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","width":682,"height":178,"caption":"KimmelPsychology"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/KimmelPsychology"]},{"@type":"Person","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a","name":"DrJoel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","caption":"DrJoel"},"sameAs":["https:\/\/kimmelpsychology.com","www. facebook.com\/Kimmelpsychology"]}]}},"_links":{"self":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/10800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/comments?post=10800"}],"version-history":[{"count":1,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/10800\/revisions"}],"predecessor-version":[{"id":10804,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/10800\/revisions\/10804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media\/10801"}],"wp:attachment":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media?parent=10800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/categories?post=10800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/tags?post=10800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}