{"id":9571,"date":"2024-08-21T16:51:42","date_gmt":"2024-08-21T20:51:42","guid":{"rendered":"https:\/\/kimmelpsychology.com\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/"},"modified":"2024-08-21T16:51:42","modified_gmt":"2024-08-21T20:51:42","slug":"temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos","status":"publish","type":"post","link":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/","title":{"rendered":"Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos!"},"content":{"rendered":"<p>Un Bolet\u00edn Electr\u00f3nico de Salud Mental de Joel I. Kimmel, Ph.D., P.A. &amp; Associates<\/strong>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;  Volumen 18, N\u00famero 8<\/p>\n<p>La e-Carta de este mes trata de c\u00f3mo crear felicidad en un mundo lleno de ira y divisi\u00f3n, es decir, la temporada electoral. Las elecciones tienden a aumentar nuestro estr\u00e9s y nos dificultan ser felices en general. Los conflictos pol\u00edticos extremadamente elevados y la excesiva cobertura medi\u00e1tica elevan nuestro estr\u00e9s a niveles muy altos.    <\/p>\n<p>Durante esta temporada electoral, nos hemos condicionado a preocuparnos por casi todo y por todo, a menudo con el consiguiente enfado. Esto puede provocar numerosas dolencias f\u00edsicas, como dolores de cabeza, hipertensi\u00f3n y agravamiento de otras afecciones m\u00e9dicas.   <\/p>\n<p>Entonces, \u00bfc\u00f3mo podemos alcanzar la felicidad durante esta temporada electoral, as\u00ed como en otras ocasiones?  <\/p>\n<p>La felicidad tiene que empezar por tomar una decisi\u00f3n consciente de ser feliz y minimizar los acontecimientos estresantes. Muchos de nosotros pensamos que adquirir m\u00e1s dinero, posesiones o estatus nos har\u00e1 felices. Pero esto es incorrecto si no estamos contentos y en paz con nosotros mismos.  <\/p>\n<p>Encontrar esa satisfacci\u00f3n y tranquilidad proviene de apreciar qui\u00e9nes somos, con qui\u00e9nes nos relacionamos y c\u00f3mo estamos viviendo en este momento. Ser feliz requiere algunas acciones muy concretas.   <\/p>\n<p>La e-Carta de este mes ofrece informaci\u00f3n sobre c\u00f3mo puedes crear felicidad en un mundo lleno de conflictos. Aseg\u00farate de leer el \u00faltimo blog del Dr. Kimmel, <em>Recuerdos de Woodstock<\/em>, <a href=\"https:\/\/kimmelpsychology.com\/es\/21-8-24-recuerdos-de-woodstock\/\"><strong>aqu\u00ed<\/strong><\/a>. <\/p>\n<p>KimmelPsychology est\u00e1 a disposici\u00f3n de quien necesite apoyo, terapia, asesoramiento, coaching profesional y evaluaciones psicol\u00f3gicas y psicoeducativas. Practicamos la telesalud y las visitas seguras en consulta. Para concertar una cita, ll\u00e1manos al 954 755-2885. Se Habla Espa\u00f1ol.   <\/p>\n<p><strong>CONSULTA EDUCATIVA<\/strong><br \/>\n\u00bfTe preocupa el rendimiento o el comportamiento de tu hijo o nieto en el nuevo curso escolar? Si crees que est\u00e1 teniendo alguna dificultad o no est\u00e1 rindiendo a la altura de sus capacidades, ahora es sin duda el momento de consultar a un profesional. Intervenir pronto puede evitar que un posible problema se agrave a medida que avanza el curso escolar.  <\/p>\n<p>Susan Flax es psic\u00f3loga escolar licenciada con amplia experiencia en la evaluaci\u00f3n de ni\u00f1os, adolescentes y adultos j\u00f3venes. Ha realizado pruebas de superdotaci\u00f3n, inteligencia, espectro autista, d\u00e9ficit de atenci\u00f3n, depresi\u00f3n y trastornos de ansiedad. Sabe exactamente lo que se necesita para garantizar que tu hijo reciba intervenciones y adaptaciones, si las necesita, lo antes posible. Puedes ponerte en contacto con la Sra. Flax en el 954 755-2885 para responder a tus preguntas o concertar una cita.   <\/p>\n<p><strong>COACHING<\/strong><br \/>\nMeredith Kimmel, PCC, present\u00f3 recientemente su taller <em>Own Your Career<\/em> a una importante organizaci\u00f3n sanitaria de Portland, Oreg\u00f3n. Tuvo tan buena acogida que volver\u00e1 en septiembre para presentar de nuevo el taller. Para obtener m\u00e1s informaci\u00f3n sobre sus conferencias y programas de coaching, puedes ponerte en contacto con Meredith en <a href=\"mailto:mk@MeredithKimmel.com\">MK@MeredithKimmel.com<\/a> o en el 954 655-7066.  <\/p>\n<h2>  Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos!<\/h2>\n<p><img data-opt-id=724075721  fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:494\/h:540\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2020\/03\/bruce-mars.jpg\" alt=\"\" width=\"375\" height=\"400\" class=\"aligncenter size-medium wp-image-2790\"><\/p>\n<p>Muchos de nosotros vivimos vidas muy dif\u00edciles y preocupantes, que se agravan en tiempos de conflicto nacional. Sin embargo, otros encuentran cada d\u00eda una felicidad que les permite disfrutar de sus vidas. Pero, \u00bfc\u00f3mo ocurre esto? \u00bfPor qu\u00e9 algunas personas parecen ser optimistas y felices casi todo el tiempo, mientras que otros estamos agobiados por la preocupaci\u00f3n, la ira y la frustraci\u00f3n?   <\/p>\n<p>La respuesta est\u00e1 en c\u00f3mo pensamos y en las elecciones que hacemos. A menudo, no podemos hacer mucho sobre lo que ocurre en nuestra naci\u00f3n. Sin embargo, ser feliz es una elecci\u00f3n activa que podemos hacer a pesar de lo que ocurre a nuestro alrededor.    <\/p>\n<p>Podemos seguir siendo felices a pesar de los \u00aby si&#8230;\u00bb y de la pesadumbre de otros que predicen lo mal que ir\u00e1n las cosas si gana uno u otro partido pol\u00edtico.<\/p>\n<p>La forma de ser feliz es tomar las riendas de tu propia vida y tomar la decisi\u00f3n consciente de ser feliz a pesar de los detractores que te rodean.  <\/p>\n<p>C\u00f3mo pienses determinar\u00e1 c\u00f3mo te sientas, y es algo sobre lo que tienes control. No desperdicies ni un d\u00eda m\u00e1s de tu vida preocup\u00e1ndote por lo que pueda ocurrir. Puede que tengas poco impacto en el mundo que te rodea, pero puedes tener un gran impacto en tu propio pensamiento.    <\/p>\n<p>En lugar de preocuparte por cosas sobre las que no tienes control, acepta que esas cosas ocurren e intenta sacarles el m\u00e1ximo partido. No dejes que te desv\u00eden de tu camino personal. Si lo hacen, vuelve a tu filosof\u00eda de vida tan pronto como puedas. Mira el panorama general de c\u00f3mo est\u00e1s viviendo y c\u00f3mo puedes mejorar tu vida.   <\/p>\n<p>Las acciones que puedes emprender para encontrar la felicidad incluyen no mirar\/escuchar fuentes de preocupaci\u00f3n, como las noticias y las redes sociales, que te dicen lo que va a ocurrir pero que rara vez ocurre. Practica afirmaciones como \u00abHoy ser\u00e9 feliz y disfrutar\u00e9 de mi d\u00eda\u00bb. Socializa con personas positivas y optimistas y no hables de pol\u00edtica. F\u00edjate un objetivo personal y cons\u00edguelo. Haz ejercicio, come bien y duerme lo suficiente.    <\/p>\n<p>Tus pensamientos pueden ser herramientas muy poderosas. Si te mantienes negativo o rumias algo, te quedar\u00e1s estancado y te consumir\u00e1 el estr\u00e9s. Puedes ser feliz desarrollando y manteniendo patrones de pensamiento positivos.  <\/p>\n<p>Recuerda que los pronosticadores pol\u00edticos predicen el desastre si gana el otro partido. \u00bfPero c\u00f3mo saben lo que ocurrir\u00e1? Incluso los pol\u00edticos prometen una cosa y a menudo cumplen otra. Investiga por tu cuenta y toma tus propias decisiones.     <\/p>\n<p>Te ofrecemos la siguiente informaci\u00f3n:<\/p>\n<h2>Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos!  <\/h2>\n<p><em><span class=\"\u201dquote\u201d\">  Puede que no controles todos los acontecimientos que te suceden, pero puedes decidir no reducirte por ellos&#8230; Maya Angelou<span class=\"\u201dauthor\u201d\"><\/span><\/span><\/em><\/p>\n<h2>LO QUE HAY QUE SABER<\/h2>\n<ul>\n<li>Las personas est\u00e1n llenas de emociones positivas y negativas; ser feliz implica reducir las emociones negativas y aumentar las positivas<\/li>\n<li>Ser feliz no se consigue f\u00e1cilmente; es una elecci\u00f3n definitiva, activa y consciente que hacen las personas<\/li>\n<li>La felicidad no es un punto final, sino un viaje continuo de autorreflexi\u00f3n y pensamiento positivo<\/li>\n<li>Para ser feliz, hay que desarrollar la mentalidad de tener pensamientos positivos al tiempo que se reducen los mensajes negativos de las noticias y las redes sociales<\/li>\n<li>Las personas felices creen que ahora es el momento de disfrutar de la vida; no esperan a que su felicidad llegue en alg\u00fan momento del futuro<\/li>\n<li>Vivir seg\u00fan una determinada filosof\u00eda positiva de la vida, a pesar de lo que hagan los dem\u00e1s, te aportar\u00e1 satisfacci\u00f3n y disfrute<\/li>\n<li>Sentir gratitud por lo que tienes, en lugar de desear m\u00e1s y m\u00e1s, te aportar\u00e1 satisfacci\u00f3n y satisfacci\u00f3n<\/li>\n<\/ul>\n<h2>\u00a1QU\u00c9 HACER!<\/h2>\n<ul>\n<li>Toma la decisi\u00f3n consciente de ser feliz en estos tiempos estresantes<\/li>\n<li>Practica afirmaciones diarias como \u00abHoy tendr\u00e9 un gran d\u00eda\u00bb.  <\/li>\n<li>C\u00e9ntrate en lo que puedes controlar y en las acciones positivas que puedes emprender<\/li>\n<li>Ver a los amigos\/familiares no como adversarios, sino como personas con puntos de vista pol\u00edticos diferentes<\/li>\n<li>Establece y mant\u00e9n tus propios l\u00edmites<\/li>\n<li>Reduce o deja por completo de ver\/escuchar fuentes de preocupaci\u00f3n, ira, ansiedad, etc.  <\/li>\n<li>Socializa con personas positivas para sentir su cari\u00f1o y su inter\u00e9s genuino por tu vida<\/li>\n<li>Elige una actividad que te guste y hazla con regularidad<\/li>\n<li>Practica el autocuidado comiendo bien, haciendo ejercicio y meditando<\/li>\n<li>Busca ayuda profesional si experimentas ansiedad continua, depresi\u00f3n o eres incapaz de encontrar la felicidad<\/li>\n<\/ul>\n<p>&nbsp;<br \/>\n<b>EJERCEMOS TANTO EN CONSULTA COMO EN TELESALUD; \u00a1PODEMOS AYUDARTE! <\/b><br \/>\nLl\u00e1manos al <strong>954 755-2885<\/strong> o env\u00edanos un correo electr\u00f3nico a <a href=\"mailto:info@KimmelPsychology.com\">info@KimmelPsychology.com<\/a><br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Doctor Joel I. Kimmel, P.A. y Asociados<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;  5551 N University Drive, Suite 202<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;  Coral Springs FL 33067<\/p>\n<p>Como siempre, nos interesan tus opiniones. Si quieres responder a esta e-Carta, env\u00eda tus comentarios por correo electr\u00f3nico a <a href=\"mailto:drKimmel@Kimmelpsychology.com\">DrKimmel@Kimmelpsychology.com <\/a> y los publicaremos el mes que viene. <\/p>\n<p>Hasta septiembre&#8230;<\/p>\n<p>La informaci\u00f3n facilitada en este bolet\u00edn electr\u00f3nico no sustituye al tratamiento profesional. Se trata de las opiniones de los redactores y se proporciona \u00fanicamente con fines educativos. Para recibir atenci\u00f3n de salud mental, acude a un profesional cualificado.  <\/p>\n<p>Si ya no deseas recibir futuros recordatorios de la e-Carta, env\u00eda un correo electr\u00f3nico a <a href=\"mailto:DrKimmel@KimmelPsychology.com\">DrKimmel@KimmelPsychology.com.<\/a> solicitando que se te elimine de esta lista.<br \/>\n&nbsp;<br \/>\nSi esta informaci\u00f3n te parece interesante o \u00fatil, reenv\u00eda esta E-Carta a tus contactos y amigos.<br \/>\n&nbsp;<br \/>\nCopyright \u00a9 2024 por Joel I. Kimmel, Ph.D. P.A. y Asociados. <\/p>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un Bolet\u00edn Electr\u00f3nico de Salud Mental de Joel I. Kimmel, Ph.D., P.A. &amp; Associates&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Volumen 18, N\u00famero 8 La e-Carta de este mes trata de c\u00f3mo crear felicidad en un mundo lleno de ira y divisi\u00f3n, es decir, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9504,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":["post-9571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos! - Kimmel Psychology<\/title>\n<meta name=\"description\" content=\"Las elecciones aumentan el estr\u00e9s, lo que dificulta ser feliz. La felicidad empieza con la intenci\u00f3n de ser feliz y minimizando los acontecimientos estresantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos! - Kimmel Psychology\" \/>\n<meta property=\"og:description\" content=\"Las elecciones aumentan el estr\u00e9s, lo que dificulta ser feliz. La felicidad empieza con la intenci\u00f3n de ser feliz y minimizando los acontecimientos estresantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/\" \/>\n<meta property=\"og:site_name\" content=\"Kimmel Psychology\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/KimmelPsychology\" \/>\n<meta property=\"article:author\" content=\"www. facebook.com\/Kimmelpsychology\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-21T20:51:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/08\/anxious-woman.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DrJoel\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DrJoel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/\"},\"author\":{\"name\":\"DrJoel\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\"},\"headline\":\"Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos!\",\"datePublished\":\"2024-08-21T20:51:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/\"},\"wordCount\":1543,\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2024\\/08\\/anxious-woman.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/\",\"name\":\"Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos! - Kimmel Psychology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2024\\/08\\/anxious-woman.jpg\",\"datePublished\":\"2024-08-21T20:51:42+00:00\",\"description\":\"Las elecciones aumentan el estr\u00e9s, lo que dificulta ser feliz. La felicidad empieza con la intenci\u00f3n de ser feliz y minimizando los acontecimientos estresantes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/#primaryimage\",\"url\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2024\\/08\\/anxious-woman.jpg\",\"contentUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2024\\/08\\/anxious-woman.jpg\",\"width\":600,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/kimmelhogar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"name\":\"Kimmel Psychology\",\"description\":\"Providing Psychological Services for Over 45 Years\",\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\",\"name\":\"KimmelPsychology\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"contentUrl\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"width\":682,\"height\":178,\"caption\":\"KimmelPsychology\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/KimmelPsychology\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\",\"name\":\"DrJoel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"caption\":\"DrJoel\"},\"sameAs\":[\"https:\\\/\\\/kimmelpsychology.com\",\"www. facebook.com\\\/Kimmelpsychology\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos! - Kimmel Psychology","description":"Las elecciones aumentan el estr\u00e9s, lo que dificulta ser feliz. La felicidad empieza con la intenci\u00f3n de ser feliz y minimizando los acontecimientos estresantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/","og_locale":"es_ES","og_type":"article","og_title":"Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos! - Kimmel Psychology","og_description":"Las elecciones aumentan el estr\u00e9s, lo que dificulta ser feliz. La felicidad empieza con la intenci\u00f3n de ser feliz y minimizando los acontecimientos estresantes.","og_url":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/","og_site_name":"Kimmel Psychology","article_publisher":"http:\/\/www.facebook.com\/KimmelPsychology","article_author":"www. facebook.com\/Kimmelpsychology","article_published_time":"2024-08-21T20:51:42+00:00","og_image":[{"width":600,"height":336,"url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/08\/anxious-woman.jpg","type":"image\/jpeg"}],"author":"DrJoel","twitter_misc":{"Escrito por":"DrJoel","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/#article","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/"},"author":{"name":"DrJoel","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a"},"headline":"Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos!","datePublished":"2024-08-21T20:51:42+00:00","mainEntityOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/"},"wordCount":1543,"publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/08\/anxious-woman.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/","url":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/","name":"Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos! - Kimmel Psychology","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/#primaryimage"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/08\/anxious-woman.jpg","datePublished":"2024-08-21T20:51:42+00:00","description":"Las elecciones aumentan el estr\u00e9s, lo que dificulta ser feliz. La felicidad empieza con la intenci\u00f3n de ser feliz y minimizando los acontecimientos estresantes.","breadcrumb":{"@id":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/#primaryimage","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/08\/anxious-woman.jpg","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/08\/anxious-woman.jpg","width":600,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/kimmelpsychology.com\/es\/temporada-electoral-crear-felicidad-en-un-mundo-lleno-de-conflictos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kimmelpsychology.com\/es\/kimmelhogar\/"},{"@type":"ListItem","position":2,"name":"Temporada electoral: \u00a1Crear Felicidad en un Mundo Lleno de Conflictos!"}]},{"@type":"WebSite","@id":"https:\/\/kimmelpsychology.com\/es\/#website","url":"https:\/\/kimmelpsychology.com\/es\/","name":"Kimmel Psychology","description":"Providing Psychological Services for Over 45 Years","publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimmelpsychology.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kimmelpsychology.com\/es\/#organization","name":"KimmelPsychology","url":"https:\/\/kimmelpsychology.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","width":682,"height":178,"caption":"KimmelPsychology"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/KimmelPsychology"]},{"@type":"Person","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a","name":"DrJoel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","caption":"DrJoel"},"sameAs":["https:\/\/kimmelpsychology.com","www. facebook.com\/Kimmelpsychology"]}]}},"_links":{"self":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/comments?post=9571"}],"version-history":[{"count":0,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media\/9504"}],"wp:attachment":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media?parent=9571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/categories?post=9571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/tags?post=9571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}