{"id":9573,"date":"2024-10-20T19:57:28","date_gmt":"2024-10-20T23:57:28","guid":{"rendered":"https:\/\/kimmelpsychology.com\/21-10-2024-politica-y-negocios\/"},"modified":"2024-10-20T19:57:28","modified_gmt":"2024-10-20T23:57:28","slug":"21-10-2024-politica-y-negocios","status":"publish","type":"post","link":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/","title":{"rendered":"21-10-2024 \u00a1Pol\u00edtica y negocios!"},"content":{"rendered":"<p>La pol\u00edtica y las pr\u00f3ximas elecciones han sido buenas para mi negocio, pero bastante desafortunadas para nuestra sociedad. Muchos de nuestros pacientes buscan alivio para la ansiedad, la depresi\u00f3n y la ira, y al final acaban hablando de las elecciones. Ahora es dif\u00edcil encontrar un terapeuta que tenga disponibilidad y adem\u00e1s acepte el seguro.<\/p>\n<p>Muchos pacientes est\u00e1n confusos sobre lo que oyen y ven. De hecho, informan de diferentes interpretaciones del mismo acontecimiento debido a c\u00f3mo lo han hilado las campa\u00f1as y los medios de comunicaci\u00f3n.  <\/p>\n<p>He visto a parejas de larga duraci\u00f3n romper o guardarse rencor mutuamente por haber decidido a qui\u00e9n votar. Otros pacientes informan de que se niegan rotundamente a ver o hablar con compa\u00f1eros de trabajo o familiares debido a sus opciones electorales.  <\/p>\n<p>La verdad y el respeto se han convertido en v\u00edctimas tempranas de las diferentes campa\u00f1as con ataques personales, historias inventadas y manipulaciones descaradas de los candidatos y los votantes. Es f\u00e1cil culpar de ello a un candidato concreto, pero en realidad, en mi opini\u00f3n, todos exageran al menos la verdad, cuando no mienten descaradamente.<\/p>\n<p>La repetici\u00f3n de los mismos anuncios pol\u00edticos pagados s\u00f3lo parece desgastar la resistencia de la gente y puede tener un efecto adormecedor y condicionante en nuestros procesos de pensamiento.  <\/p>\n<p>Es como el lavado de cerebro, en el sentido de que si te repiten la misma mentira una y otra vez, una persona tiende a creerla, sobre todo si est\u00e1 avalada por una figura medi\u00e1tica. Cuanto m\u00e1s chocantes son los anuncios pol\u00edticos, m\u00e1s atenci\u00f3n parecen recibir.  <\/p>\n<p>Con raz\u00f3n o sin ella, los estados emocionales de nuestros pacientes se han agravado con sentimientos declarados de impotencia, miedo e ira. A la pregunta \u00ab\u00bfqu\u00e9 puedo hacer?\u00bb le sigue un encogimiento de hombros y una aceptaci\u00f3n a rega\u00f1adientes de la situaci\u00f3n actual.  <\/p>\n<p>Ir\u00f3nicamente, como psic\u00f3loga, trabajo para capacitar a mis pacientes con nuevas formas de pensar y comportarse para resolver sus problemas y desescalar sus sentimientos negativos. Trabajamos para evitar las situaciones perjudiciales y negativas y para aprender a manejarlas cuando se producen.  <\/p>\n<p> <img data-opt-id=307233621  fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:501\/h:540\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/10\/pexels-moose-photos.jpg\" alt=\"\" width=\"260\" height=\"300\" class=\"aligncenter size-medium wp-image-8676\"><\/p>\n<p>Modelamos el respeto por nosotros mismos y por los dem\u00e1s. Desarrollamos estrategias para tratar con personas y situaciones dif\u00edciles y desarrollamos formas de manejar la ansiedad, la ira y la frustraci\u00f3n. Animamos a decir la verdad y a tener amabilidad y respeto por los dem\u00e1s.<\/p>\n<p>Tambi\u00e9n es el momento de que cada uno de nosotros, individualmente, asumamos la responsabilidad de mejorar la sociedad con nuestra forma de vivir y siendo un ejemplo de respeto y decencia. No podemos esperar a que los l\u00edderes e influyentes de la sociedad den ejemplo, porque a\u00fan no lo han hecho y probablemente no lo har\u00e1n.  <\/p>\n<p>Creo que s\u00f3lo cada uno de nosotros puede reparar el mundo a su manera.  <\/p>\n<p>El clima pol\u00edtico y social actual nos ha dado mucho trabajo.<\/p>\n<p>\u00bfComentarios? H\u00e1zmelo saber en <a href=\"mailto:DrKimmel@KimmelPsychology.com\">DrKimmel@KimmelPsychology.com.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pol\u00edtica y las pr\u00f3ximas elecciones han sido buenas para mi negocio, pero bastante desafortunadas para nuestra sociedad. Muchos de nuestros pacientes buscan alivio para la ansiedad, la depresi\u00f3n y la ira, y al final acaban hablando de las elecciones. Ahora es dif\u00edcil encontrar un terapeuta que tenga disponibilidad y adem\u00e1s acepte el seguro. Muchos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9513,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[158],"tags":[],"class_list":["post-9573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>21-10-2024 \u00a1Pol\u00edtica y negocios! - Kimmel Psychology<\/title>\n<meta name=\"description\" content=\"La pol\u00edtica y las elecciones han sido desafortunadas para la sociedad, pero buenas para los negocios, ya que es dif\u00edcil encontrar un terapeuta con disponibilidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"21-10-2024 \u00a1Pol\u00edtica y negocios! - Kimmel Psychology\" \/>\n<meta property=\"og:description\" content=\"La pol\u00edtica y las elecciones han sido desafortunadas para la sociedad, pero buenas para los negocios, ya que es dif\u00edcil encontrar un terapeuta con disponibilidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/\" \/>\n<meta property=\"og:site_name\" content=\"Kimmel Psychology\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/KimmelPsychology\" \/>\n<meta property=\"article:author\" content=\"www. facebook.com\/Kimmelpsychology\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-20T23:57:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/10\/couple.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"427\" \/>\n\t<meta property=\"og:image:height\" content=\"237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DrJoel\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DrJoel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/\"},\"author\":{\"name\":\"DrJoel\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\"},\"headline\":\"21-10-2024 \u00a1Pol\u00edtica y negocios!\",\"datePublished\":\"2024-10-20T23:57:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/\"},\"wordCount\":520,\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2024\\/10\\/couple.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/\",\"name\":\"21-10-2024 \u00a1Pol\u00edtica y negocios! - Kimmel Psychology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2024\\/10\\/couple.jpg\",\"datePublished\":\"2024-10-20T23:57:28+00:00\",\"description\":\"La pol\u00edtica y las elecciones han sido desafortunadas para la sociedad, pero buenas para los negocios, ya que es dif\u00edcil encontrar un terapeuta con disponibilidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/#primaryimage\",\"url\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2024\\/10\\/couple.jpg\",\"contentUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2024\\/10\\/couple.jpg\",\"width\":427,\"height\":237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-10-2024-politica-y-negocios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/kimmelhogar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"21-10-2024 \u00a1Pol\u00edtica y negocios!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"name\":\"Kimmel Psychology\",\"description\":\"Providing Psychological Services for Over 45 Years\",\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\",\"name\":\"KimmelPsychology\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"contentUrl\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"width\":682,\"height\":178,\"caption\":\"KimmelPsychology\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/KimmelPsychology\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\",\"name\":\"DrJoel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"caption\":\"DrJoel\"},\"sameAs\":[\"https:\\\/\\\/kimmelpsychology.com\",\"www. facebook.com\\\/Kimmelpsychology\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"21-10-2024 \u00a1Pol\u00edtica y negocios! - Kimmel Psychology","description":"La pol\u00edtica y las elecciones han sido desafortunadas para la sociedad, pero buenas para los negocios, ya que es dif\u00edcil encontrar un terapeuta con disponibilidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/","og_locale":"es_ES","og_type":"article","og_title":"21-10-2024 \u00a1Pol\u00edtica y negocios! - Kimmel Psychology","og_description":"La pol\u00edtica y las elecciones han sido desafortunadas para la sociedad, pero buenas para los negocios, ya que es dif\u00edcil encontrar un terapeuta con disponibilidad.","og_url":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/","og_site_name":"Kimmel Psychology","article_publisher":"http:\/\/www.facebook.com\/KimmelPsychology","article_author":"www. facebook.com\/Kimmelpsychology","article_published_time":"2024-10-20T23:57:28+00:00","og_image":[{"width":427,"height":237,"url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/10\/couple.jpg","type":"image\/jpeg"}],"author":"DrJoel","twitter_misc":{"Escrito por":"DrJoel","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/#article","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/"},"author":{"name":"DrJoel","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a"},"headline":"21-10-2024 \u00a1Pol\u00edtica y negocios!","datePublished":"2024-10-20T23:57:28+00:00","mainEntityOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/"},"wordCount":520,"publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/10\/couple.jpg","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/","url":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/","name":"21-10-2024 \u00a1Pol\u00edtica y negocios! - Kimmel Psychology","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/#primaryimage"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/10\/couple.jpg","datePublished":"2024-10-20T23:57:28+00:00","description":"La pol\u00edtica y las elecciones han sido desafortunadas para la sociedad, pero buenas para los negocios, ya que es dif\u00edcil encontrar un terapeuta con disponibilidad.","breadcrumb":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/#primaryimage","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/10\/couple.jpg","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2024\/10\/couple.jpg","width":427,"height":237},{"@type":"BreadcrumbList","@id":"https:\/\/kimmelpsychology.com\/es\/21-10-2024-politica-y-negocios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kimmelpsychology.com\/es\/kimmelhogar\/"},{"@type":"ListItem","position":2,"name":"21-10-2024 \u00a1Pol\u00edtica y negocios!"}]},{"@type":"WebSite","@id":"https:\/\/kimmelpsychology.com\/es\/#website","url":"https:\/\/kimmelpsychology.com\/es\/","name":"Kimmel Psychology","description":"Providing Psychological Services for Over 45 Years","publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimmelpsychology.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kimmelpsychology.com\/es\/#organization","name":"KimmelPsychology","url":"https:\/\/kimmelpsychology.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","width":682,"height":178,"caption":"KimmelPsychology"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/KimmelPsychology"]},{"@type":"Person","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a","name":"DrJoel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","caption":"DrJoel"},"sameAs":["https:\/\/kimmelpsychology.com","www. facebook.com\/Kimmelpsychology"]}]}},"_links":{"self":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/comments?post=9573"}],"version-history":[{"count":0,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media\/9513"}],"wp:attachment":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media?parent=9573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/categories?post=9573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/tags?post=9573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}