{"id":9715,"date":"2023-04-21T19:49:03","date_gmt":"2023-04-21T23:49:03","guid":{"rendered":"https:\/\/kimmelpsychology.com\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/"},"modified":"2023-04-21T19:49:03","modified_gmt":"2023-04-21T23:49:03","slug":"21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion","status":"publish","type":"post","link":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/","title":{"rendered":"21 de abril de 2023 &#8211; \u00a1Reportaje de noticias en los medios de comunicaci\u00f3n!"},"content":{"rendered":"<p>El blog de este mes se escribi\u00f3 en realidad hace 5 a\u00f1os para la e-Carta de enero de 2018. Lo vuelvo a publicar aqu\u00ed porque la situaci\u00f3n es muy parecida, si no peor. Mucha gente sigue sinti\u00e9ndose frustrada, enfadada e impotente ante la forma en que los medios de comunicaci\u00f3n informan de las noticias.  <\/p>\n<p>20 de enero de 2018<\/p>\n<p>Durante el \u00faltimo a\u00f1o, muchos de mis pacientes han acudido a sus sesiones enfadados por la pol\u00edtica. No importa a qu\u00e9 partido pertenezcan o si son de derechas, de izquierdas o de centro, todos est\u00e1n enfadados y frustrados.   <\/p>\n<p>Se sienten impotentes y preocupados por el futuro de nuestro pa\u00eds y de ellos mismos. Tal vez, con raz\u00f3n. Han pasado muchas horas de conversaci\u00f3n intentando reducir su ira y centrarse en su vida cotidiana.    <\/p>\n<p>Una de las sugerencias que han surgido de nuestros debates parece funcionar. Se trata de reducir o eliminar el n\u00famero de horas que pasamos viendo las noticias en la televisi\u00f3n o escuch\u00e1ndolas en la radio. <\/p>\n<p>No importa qu\u00e9 cadena veas o escuches. Todas parecen empe\u00f1adas en suscitar sentimientos de injusticia y rabia, pero no ofrecen ninguna soluci\u00f3n. Supongo que el objetivo final es tener a los espectadores u oyentes pegados a sus emisoras.    <\/p>\n<p>Tal vez se trate de una adicci\u00f3n a los medios de comunicaci\u00f3n. Sin embargo, no hay subid\u00f3n, sino s\u00f3lo preocupaci\u00f3n y rabia.   <\/p>\n<p>Hace poco le\u00ed un art\u00edculo sobre un apag\u00f3n informativo autoimpuesto por Christopher Hebert, profesor adjunto de Ingl\u00e9s en la Universidad de Tennessee, en la edici\u00f3n del 18 de enero de The Guardian.  <\/p>\n<p>Lo que sigue es un extracto:<br \/>\n<em>La ignorancia es mucho m\u00e1s f\u00e1cil de lo que pensaba. Termino dos o tres audiolibros a la semana. Leo novelas en lugar de peri\u00f3dicos. Cinco meses despu\u00e9s de mi desmayo, soy m\u00e1s feliz que en los d\u00edas en que estaba informada. Me vuelven a crecer las u\u00f1as. Los somn\u00edferos siguen en el frasco. Trabajo m\u00e1s. Mi familia llega a casa al final del d\u00eda y me encuentra sonriendo, cortando cosas para la cena sin mi antigua rabia regicida.        Y, sin embargo, una parte de m\u00ed no puede dejar de sentirse culpable por sentirse bien.<\/em><\/p>\n<p>Tal vez, \u00e9sta sea una soluci\u00f3n al enfado y la frustraci\u00f3n de los medios de comunicaci\u00f3n al informar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El blog de este mes se escribi\u00f3 en realidad hace 5 a\u00f1os para la e-Carta de enero de 2018. Lo vuelvo a publicar aqu\u00ed porque la situaci\u00f3n es muy parecida, si no peor. Mucha gente sigue sinti\u00e9ndose frustrada, enfadada e impotente ante la forma en que los medios de comunicaci\u00f3n informan de las noticias. 20 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9419,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[158],"tags":[],"class_list":["post-9715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>21 de abril de 2023 - \u00a1Reportaje de noticias en los medios de comunicaci\u00f3n! - Kimmel Psychology<\/title>\n<meta name=\"description\" content=\"Mucha gente est\u00e1 enfadada y frustrada por las noticias de los medios de comunicaci\u00f3n, que crean miedo y preocupaci\u00f3n y no ofrecen soluciones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"21 de abril de 2023 - \u00a1Reportaje de noticias en los medios de comunicaci\u00f3n! - Kimmel Psychology\" \/>\n<meta property=\"og:description\" content=\"Mucha gente est\u00e1 enfadada y frustrada por las noticias de los medios de comunicaci\u00f3n, que crean miedo y preocupaci\u00f3n y no ofrecen soluciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Kimmel Psychology\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/KimmelPsychology\" \/>\n<meta property=\"article:author\" content=\"www. facebook.com\/Kimmelpsychology\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-21T23:49:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2023\/04\/andrea-piacquadio-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1793\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DrJoel\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DrJoel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/\"},\"author\":{\"name\":\"DrJoel\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\"},\"headline\":\"21 de abril de 2023 &#8211; \u00a1Reportaje de noticias en los medios de comunicaci\u00f3n!\",\"datePublished\":\"2023-04-21T23:49:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/\"},\"wordCount\":422,\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2023\\/04\\/andrea-piacquadio-scaled.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/\",\"name\":\"21 de abril de 2023 - \u00a1Reportaje de noticias en los medios de comunicaci\u00f3n! - Kimmel Psychology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2023\\/04\\/andrea-piacquadio-scaled.jpg\",\"datePublished\":\"2023-04-21T23:49:03+00:00\",\"description\":\"Mucha gente est\u00e1 enfadada y frustrada por las noticias de los medios de comunicaci\u00f3n, que crean miedo y preocupaci\u00f3n y no ofrecen soluciones.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/#primaryimage\",\"url\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2023\\/04\\/andrea-piacquadio-scaled.jpg\",\"contentUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2023\\/04\\/andrea-piacquadio-scaled.jpg\",\"width\":2560,\"height\":1793},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/kimmelhogar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"21 de abril de 2023 &#8211; \u00a1Reportaje de noticias en los medios de comunicaci\u00f3n!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"name\":\"Kimmel Psychology\",\"description\":\"Providing Psychological Services for Over 45 Years\",\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\",\"name\":\"KimmelPsychology\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"contentUrl\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"width\":682,\"height\":178,\"caption\":\"KimmelPsychology\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/KimmelPsychology\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\",\"name\":\"DrJoel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"caption\":\"DrJoel\"},\"sameAs\":[\"https:\\\/\\\/kimmelpsychology.com\",\"www. facebook.com\\\/Kimmelpsychology\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"21 de abril de 2023 - \u00a1Reportaje de noticias en los medios de comunicaci\u00f3n! - Kimmel Psychology","description":"Mucha gente est\u00e1 enfadada y frustrada por las noticias de los medios de comunicaci\u00f3n, que crean miedo y preocupaci\u00f3n y no ofrecen soluciones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/","og_locale":"es_ES","og_type":"article","og_title":"21 de abril de 2023 - \u00a1Reportaje de noticias en los medios de comunicaci\u00f3n! - Kimmel Psychology","og_description":"Mucha gente est\u00e1 enfadada y frustrada por las noticias de los medios de comunicaci\u00f3n, que crean miedo y preocupaci\u00f3n y no ofrecen soluciones.","og_url":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/","og_site_name":"Kimmel Psychology","article_publisher":"http:\/\/www.facebook.com\/KimmelPsychology","article_author":"www. facebook.com\/Kimmelpsychology","article_published_time":"2023-04-21T23:49:03+00:00","og_image":[{"width":2560,"height":1793,"url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2023\/04\/andrea-piacquadio-scaled.jpg","type":"image\/jpeg"}],"author":"DrJoel","twitter_misc":{"Escrito por":"DrJoel","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/#article","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/"},"author":{"name":"DrJoel","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a"},"headline":"21 de abril de 2023 &#8211; \u00a1Reportaje de noticias en los medios de comunicaci\u00f3n!","datePublished":"2023-04-21T23:49:03+00:00","mainEntityOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/"},"wordCount":422,"publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2023\/04\/andrea-piacquadio-scaled.jpg","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/","url":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/","name":"21 de abril de 2023 - \u00a1Reportaje de noticias en los medios de comunicaci\u00f3n! - Kimmel Psychology","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/#primaryimage"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2023\/04\/andrea-piacquadio-scaled.jpg","datePublished":"2023-04-21T23:49:03+00:00","description":"Mucha gente est\u00e1 enfadada y frustrada por las noticias de los medios de comunicaci\u00f3n, que crean miedo y preocupaci\u00f3n y no ofrecen soluciones.","breadcrumb":{"@id":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/#primaryimage","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2023\/04\/andrea-piacquadio-scaled.jpg","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2023\/04\/andrea-piacquadio-scaled.jpg","width":2560,"height":1793},{"@type":"BreadcrumbList","@id":"https:\/\/kimmelpsychology.com\/es\/21-de-abril-de-2023-reportaje-de-noticias-en-los-medios-de-comunicacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kimmelpsychology.com\/es\/kimmelhogar\/"},{"@type":"ListItem","position":2,"name":"21 de abril de 2023 &#8211; \u00a1Reportaje de noticias en los medios de comunicaci\u00f3n!"}]},{"@type":"WebSite","@id":"https:\/\/kimmelpsychology.com\/es\/#website","url":"https:\/\/kimmelpsychology.com\/es\/","name":"Kimmel Psychology","description":"Providing Psychological Services for Over 45 Years","publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimmelpsychology.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kimmelpsychology.com\/es\/#organization","name":"KimmelPsychology","url":"https:\/\/kimmelpsychology.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","width":682,"height":178,"caption":"KimmelPsychology"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/KimmelPsychology"]},{"@type":"Person","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a","name":"DrJoel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","caption":"DrJoel"},"sameAs":["https:\/\/kimmelpsychology.com","www. facebook.com\/Kimmelpsychology"]}]}},"_links":{"self":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/comments?post=9715"}],"version-history":[{"count":0,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media\/9419"}],"wp:attachment":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media?parent=9715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/categories?post=9715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/tags?post=9715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}