{"id":9737,"date":"2022-05-22T11:27:16","date_gmt":"2022-05-22T15:27:16","guid":{"rendered":"https:\/\/kimmelpsychology.com\/vivir-con-integridad\/"},"modified":"2022-05-22T11:27:16","modified_gmt":"2022-05-22T15:27:16","slug":"vivir-con-integridad","status":"publish","type":"post","link":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/","title":{"rendered":"Vivir con integridad"},"content":{"rendered":"<p><strong>\u00bfQu\u00e9 ha sido de vivir con integridad?<\/strong> <\/p>\n<p><strong>Un Bolet\u00edn Electr\u00f3nico de Salud Mental de Joel I. Kimmel, Ph.D., P.A. &amp; Associates<\/strong><br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; <strong>Volumen 16, N\u00famero 5<\/strong><\/p>\n<p>Escuchando las noticias y otras fuentes de informaci\u00f3n, parece como si vivi\u00e9ramos en un mundo en el que la gente, especialmente nuestros l\u00edderes nacionales, se preocupan de s\u00ed mismos sin preocuparse de los dem\u00e1s.<\/p>\n<p>La filosof\u00eda general no es qu\u00e9 es lo correcto, sino que est\u00e1 bien c\u00f3mo consigas lo que quieres. El fin justifica los medios, aunque pueda perjudicar a otros o da\u00f1ar nuestras instituciones y creencias. <\/p>\n<p>Nuestra e-Carta de mayo trata sobre Vivir con Integridad. El blog del Dr. Kimmel trata sobre la Ansiedad ante el Hurac\u00e1n y puede consultarse <a href=\"https:\/\/kimmelpsychology.com\/es\/blog\/\">aqu\u00ed<\/a>. <\/p>\n<p>Esperamos que la informaci\u00f3n adjunta te resulte \u00fatil e interesante. Tambi\u00e9n te damos las gracias por leer nuestras cartas electr\u00f3nicas y por los comentarios positivos y compasivos que hemos recibido. <\/p>\n<h2>NOTICIAS PR\u00c1CTICAS<\/h2>\n<p>En respuesta a la crisis de salud mental, tenemos:<\/p>\n<li style=\"margin-left: +10px;\">a\u00f1adimos horas a los horarios de nuestros terapeutas para poder atender a m\u00e1s pacientes<\/li>\n<li style=\"margin-left: +10px;\">publicado m\u00e1s art\u00edculos \u00fatiles en nuestras p\u00e1ginas de <a href=\"https:\/\/www.facebook.com\/KimmelPsychology\/\">Facebook<\/a> y LinkedIn para apoyar a quienes se benefician de la lectura sobre salud mental<\/li>\n<li style=\"margin-left: +10px;\">un psiquiatra en plantilla para diagn\u00f3sticos y medicaci\u00f3n<\/li>\n<li style=\"margin-left: +10px;\">un coach de transformaci\u00f3n de la vida para ayudar en la adaptaci\u00f3n a cambios vitales como el duelo y la p\u00e9rdida  <\/li>\n<li style=\"margin-left: +10px;\">un psic\u00f3logo escolar que trabaja con los ni\u00f1os para ayudarles a superar cualquier dificultad de aprendizaje o emocional y puede proporcionar evaluaciones educativas<\/li>\n<p>&nbsp;<br \/>\nPracticamos la telesalud y tambi\u00e9n hemos vuelto a las visitas seguras en consulta. Puedes ponerte en contacto con nosotros llamando a nuestra consulta al <b>954 755-2885<\/b> o entrando en la p\u00e1gina <strong>Nuestro Personal<\/strong> de nuestro sitio web, <a href=\"http:\/\/www.KimmelPsychology.com\">KimmelPsychology.com<\/a>. <\/p>\n<h2>\u00a1Vivir con integridad!<\/h2>\n<p><img data-opt-id=1687701553  fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:577\/h:540\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2022\/05\/prophsee-journals.jpg\" alt=\"\" width=\"400\" height=\"380\" class=\"aligncenter size-small wp-image-7252\">&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;  (Foto de prophsee-journals)<\/p>\n<p>Nuestra capacidad de confiar en lo que o\u00edmos y en lo que vemos se ha visto da\u00f1ada. La pregunta, b\u00e1sicamente, es \u00bfen qui\u00e9n confiamos? Obviamente, esto ha empeorado debido a la pandemia.  <\/p>\n<p>Sin embargo, incluso antes de Covid, hab\u00eda numerosas mentiras y desinformaci\u00f3n. En lugar de admitir la falta de honradez, se han convertido en habituales las \u00abvueltas atr\u00e1s\u00bb, las declaraciones equivocadas y los desmentidos. La integridad se ha erosionado tanto que incluso hemos tenido que crear una ef\u00edmera Junta de Gobierno de Desinformaci\u00f3n en la que ya no se conf\u00eda ni se hace una pausa.  <\/p>\n<p>Valoramos la integridad y la buscamos en nuestros dirigentes locales, estatales y nacionales. Son personas en las que confiamos para que cumplan con su deber y nos protejan. Pero, \u00bfqu\u00e9 es realmente la integridad? Es el compromiso de vivir con principios morales y \u00e9ticos. Es honradez y confianza. Es hacer lo correcto incluso cuando nadie mira, y la elecci\u00f3n puede no ser f\u00e1cil.     <\/p>\n<p>Vivir con integridad significa que siempre somos honestos y nos comportamos de forma coherente con estos valores. Vivir con integridad es una elecci\u00f3n y a menudo se pone en tela de juicio. Cuando seguimos nuestra propia br\u00fajula moral, la vida es m\u00e1s f\u00e1cil y sencilla.    <\/p>\n<p>No tenemos que preocuparnos por las consecuencias de nuestros actos ni preocuparnos por ocultar nada. Los dem\u00e1s conf\u00edan en nosotros y a menudo nos admiran por nuestros valores. <\/p>\n<p>La integridad tambi\u00e9n incluye asumir la responsabilidad de tus pensamientos y comportamientos. Los opuestos de la integridad son el enga\u00f1o, el cotilleo, la falta de sinceridad, avergonzar a los dem\u00e1s, la mentira intencionada y la manipulaci\u00f3n. Esto suele causar angustia interna en las personas, lo que conduce a adicciones, comportamiento antisocial y depresi\u00f3n.  <\/p>\n<p>Vivir con integridad tiene beneficios sociales. Las personas \u00edntegras gozan de la confianza de los dem\u00e1s, son muy queridas, se convierten en l\u00edderes, mantienen relaciones estrechas con los dem\u00e1s y se las considera aut\u00e9nticas. Tambi\u00e9n disminuye la ansiedad y la autocr\u00edtica. Vivir con integridad tambi\u00e9n atrae a otras personas que viven con integridad.   <\/p>\n<p>Los rasgos de car\u00e1cter de las personas que viven con integridad incluyen ser respetuosas y honestas. Son amables cuando se les presta ayuda y dicen f\u00e1cilmente \u00abgracias\u00bb. Suelen ser considerados con los sentimientos de los dem\u00e1s y se esfuerzan por ser sinceros. Asumen sus errores y no se aprovechan de las desgracias ajenas. Cumplen sus compromisos y puedes contar con ellos. Suelen ser trabajadores y muy responsables de sus actos.     <\/p>\n<p>Integridad vs <strong>Desesperaci\u00f3n<\/strong><br \/>\nLa integridad vs desesperaci\u00f3n es tambi\u00e9n una de las etapas de la teor\u00eda del desarrollo psicosocial de Erik Erikson. Es la etapa final y comienza a los 65 a\u00f1os y termina con la muerte. El principal conflicto que hay que resolver se centra en el cuestionamiento personal sobre si la propia vida ten\u00eda sentido y era satisfactoria o no.    <\/p>\n<p>La integridad tambi\u00e9n se refiere a determinar si la vida de una persona fue satisfactoria y tuvo logros. Aporta una sensaci\u00f3n de paz, aceptaci\u00f3n y \u00e9xito. <\/p>\n<p>La integridad puede desarrollarse y conservarse conociendo tus valores fundamentales y ci\u00f1\u00e9ndote a ellos. Cada decisi\u00f3n que se toma es la correcta de acuerdo con tus valores, sean cuales sean las circunstancias. Desarrolla la confianza en ti mismo y la autoestima sabiendo qui\u00e9n eres y tomando las decisiones correctas. S\u00e9 asertivo y di siempre la verdad. Asume la responsabilidad de tus actos y asume tus errores.    <\/p>\n<p>Te ofrecemos la siguiente informaci\u00f3n:<\/p>\n<p><strong>\u00a1VIVIR CON INTEGRIDAD!<\/strong><br \/>\n<em><span class=\u201dquote\u201d>S\u00e9 fiel a ti mismo y, como la noche al d\u00eda, no podr\u00e1s ser falso a nadie. &#8230; Hamlet\/William Shakespeare  <span class=\"\u201dauthor\u201d\"><\/span><\/em><\/p>\n<h2>LO QUE HAY QUE SABER<\/h2>\n<ul>\n<li>  La integridad determina tu reputaci\u00f3n y c\u00f3mo te conocen<\/li>\n<li>  Se define como tener una fuerte adhesi\u00f3n a un c\u00f3digo de valores morales<\/li>\n<li>  Se trata de hacer lo correcto incluso cuando no es f\u00e1cil hacerlo o si no es reconocido por los dem\u00e1s<\/li>\n<li>  Tener integridad significa resistir la presi\u00f3n social para hacer lo que no es coherente con tu conjunto de valores; es practicar lo que predicas<\/li>\n<li>  Un componente de la integridad es el valor; la capacidad de mantener tus convicciones aunque no sean populares.<\/li>\n<li>  Tener integridad genera confianza y respeto por parte de los dem\u00e1s<\/li>\n<li>  Las personas \u00edntegras suelen caer bien, cuentan con mucho apoyo social, tienen amistades cercanas y, en general, son muy respetadas<\/li>\n<li>  Las caracter\u00edsticas de las personas \u00edntegras incluyen ser amables, respetuosas, honestas, dignas de confianza, responsables, serviciales y pacientes<\/li>\n<li>  Los comportamientos de las personas \u00edntegras incluyen no cotillear, no compartir con los dem\u00e1s los secretos que te cuentan, cumplir las promesas y admitir cuando te equivocas<\/li>\n<li>  Los opuestos de la integridad son la falta de sinceridad, la deshonestidad y el enga\u00f1o<\/li>\n<li>  La integridad tambi\u00e9n puede referirse a la sensibilidad hacia las necesidades de los dem\u00e1s; no se trata s\u00f3lo de c\u00f3mo uno piensa, sino tambi\u00e9n de su comportamiento moral<\/li>\n<li>  Los l\u00edderes \u00edntegros y responsables inspiran confianza y respeto a los dem\u00e1s; suelen ser muy eficaces y pueden motivar a la gente<\/li>\n<li>  Los padres y los profesores son las primeras fuentes de ense\u00f1anza de la integridad a los ni\u00f1os; por el contrario, las redes sociales, la televisi\u00f3n, las pel\u00edculas, la pol\u00edtica, los videojuegos y las noticias pueden ser muy destructivas para el aprendizaje del valor de la integridad.<\/li>\n<li>  La integridad tambi\u00e9n se refiere a vivir la vida con un sentido de realizaci\u00f3n y plenitud<\/li>\n<li>  En la teor\u00eda de las etapas del desarrollo psicosocial de Erik Erikson:  <\/li>\n<li style=\"margin-left: +20px;\">  la integridad frente a la desesperaci\u00f3n es la octava y \u00faltima etapa<\/li>\n<li style=\"margin-left: +20px;\">  comienza alrededor de los 65 a\u00f1os y termina con la muerte<\/li>\n<li style=\"margin-left: +20px;\">  se desencadena por acontecimientos vitales como la jubilaci\u00f3n, la p\u00e9rdida de amigos o del c\u00f3nyuge, padecer una enfermedad terminal y cualquier otro cambio vital importante<\/li>\n<li style=\"margin-left: +20px;\">  el conflicto principal es si la vida ha tenido sentido y ha sido satisfactoria<\/li>\n<\/ul>\n<h2>\u00a1QU\u00c9 HACER!<\/h2>\n<ul>\n<li>  S\u00e9 honesto contigo mismo y conoce tus valores fundamentales, aquellos que no disminuir\u00e1s ni comprometer\u00e1s<\/li>\n<li>  Toma siempre la decisi\u00f3n correcta aunque nadie te est\u00e9 mirando<\/li>\n<li>  Considera lo que publicas en Internet y c\u00f3mo quieres que los dem\u00e1s piensen de ti<\/li>\n<li>  Sigue aumentando tu autoestima y af\u00edliate a otras personas \u00edntegras<\/li>\n<li>  S\u00e9 asertivo y defiende tus valores<\/li>\n<li>  Asume tus errores y responsabil\u00edzate de lo que haces<\/li>\n<li>  Mant\u00e9n tus promesas<\/li>\n<li>  Busca ayuda profesional para construir tu integridad y mantener tu car\u00e1cter<\/li>\n<\/ul>\n<p>&nbsp;<br \/>\n<b>\u00a1PRACTICAMOS LA TELESALUD Y PODEMOS AYUDARTE! <\/b><br \/>\nLl\u00e1manos al <strong>954 755-2885<\/strong> o env\u00edanos un correo electr\u00f3nico a <a href=\"mailto:info@KimmelPsychology.com\">info@KimmelPsychology.com<\/a><\/p>\n<p>Doctor Joel I. Kimmel P.A. y Asociados<br \/>\n5551 N University Drive, Suite 202<br \/>\nCoral Springs FL 33067<\/p>\n<p>Como siempre, nos interesan tus opiniones. Si quieres responder a esta e-Carta, env\u00edame tus comentarios por correo electr\u00f3nico a <a href=\"mailto:drKimmel@Kimmelpsychology.com\">DrKimmel@Kimmelpsychology.com <\/a> y los publicar\u00e9 el mes que viene.<\/p>\n<p>Hasta junio&#8230;<\/p>\n<p>La informaci\u00f3n proporcionada en este bolet\u00edn electr\u00f3nico no sustituye al tratamiento profesional. Son las opiniones de los redactores y se facilitan \u00fanicamente con fines educativos.  Para la atenci\u00f3n a la salud mental, busca un profesional cualificado.<\/p>\n<p>Si ya no deseas recibir futuros recordatorios de la E-Letter, env\u00eda un correo electr\u00f3nico a <a href=\"mailto:drKimmel@KimmelPsychology.com\">DrKimmel@KimmelPsychology.com.<\/a> solicitando que se te elimine de esta lista.<\/p>\n<p>Si esta informaci\u00f3n te parece interesante o \u00fatil, reenv\u00eda esta E-Carta a tus contactos y amigos.  <\/p>\n<p>Copyright \u00a9 2022 por Joel I. Kimmel, Doctor en Filosof\u00eda. P.A. y Asociados.<\/p>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivir con integridad significa que siempre somos honestos y nos comportamos de forma coherente con estos valores.  <\/p>\n","protected":false},"author":3,"featured_media":9363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":["post-9737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vivir con integridad - Kimmel Psychology<\/title>\n<meta name=\"description\" content=\"Vivir con integridad significa que siempre somos honestos y nos comportamos de forma coherente con estos valores. Con integridad, la vida es m\u00e1s f\u00e1cil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vivir con integridad - Kimmel Psychology\" \/>\n<meta property=\"og:description\" content=\"Vivir con integridad significa que siempre somos honestos y nos comportamos de forma coherente con estos valores. Con integridad, la vida es m\u00e1s f\u00e1cil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/\" \/>\n<meta property=\"og:site_name\" content=\"Kimmel Psychology\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/KimmelPsychology\" \/>\n<meta property=\"article:author\" content=\"www. facebook.com\/Kimmelpsychology\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-22T15:27:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2022\/05\/nathan-lemon-1-e1653232904122.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DrJoel\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DrJoel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/\"},\"author\":{\"name\":\"DrJoel\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\"},\"headline\":\"Vivir con integridad\",\"datePublished\":\"2022-05-22T15:27:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/\"},\"wordCount\":1671,\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2022\\/05\\/nathan-lemon-1-e1653232904122.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/\",\"name\":\"Vivir con integridad - Kimmel Psychology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2022\\/05\\/nathan-lemon-1-e1653232904122.jpg\",\"datePublished\":\"2022-05-22T15:27:16+00:00\",\"description\":\"Vivir con integridad significa que siempre somos honestos y nos comportamos de forma coherente con estos valores. Con integridad, la vida es m\u00e1s f\u00e1cil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/#primaryimage\",\"url\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2022\\/05\\/nathan-lemon-1-e1653232904122.jpg\",\"contentUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2022\\/05\\/nathan-lemon-1-e1653232904122.jpg\",\"width\":400,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/vivir-con-integridad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/kimmelhogar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vivir con integridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"name\":\"Kimmel Psychology\",\"description\":\"Providing Psychological Services for Over 45 Years\",\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\",\"name\":\"KimmelPsychology\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"contentUrl\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"width\":682,\"height\":178,\"caption\":\"KimmelPsychology\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/KimmelPsychology\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\",\"name\":\"DrJoel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"caption\":\"DrJoel\"},\"sameAs\":[\"https:\\\/\\\/kimmelpsychology.com\",\"www. facebook.com\\\/Kimmelpsychology\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vivir con integridad - Kimmel Psychology","description":"Vivir con integridad significa que siempre somos honestos y nos comportamos de forma coherente con estos valores. Con integridad, la vida es m\u00e1s f\u00e1cil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/","og_locale":"es_ES","og_type":"article","og_title":"Vivir con integridad - Kimmel Psychology","og_description":"Vivir con integridad significa que siempre somos honestos y nos comportamos de forma coherente con estos valores. Con integridad, la vida es m\u00e1s f\u00e1cil.","og_url":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/","og_site_name":"Kimmel Psychology","article_publisher":"http:\/\/www.facebook.com\/KimmelPsychology","article_author":"www. facebook.com\/Kimmelpsychology","article_published_time":"2022-05-22T15:27:16+00:00","og_image":[{"width":400,"height":430,"url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2022\/05\/nathan-lemon-1-e1653232904122.jpg","type":"image\/jpeg"}],"author":"DrJoel","twitter_misc":{"Escrito por":"DrJoel","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/#article","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/"},"author":{"name":"DrJoel","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a"},"headline":"Vivir con integridad","datePublished":"2022-05-22T15:27:16+00:00","mainEntityOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/"},"wordCount":1671,"publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2022\/05\/nathan-lemon-1-e1653232904122.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/","url":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/","name":"Vivir con integridad - Kimmel Psychology","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/#primaryimage"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2022\/05\/nathan-lemon-1-e1653232904122.jpg","datePublished":"2022-05-22T15:27:16+00:00","description":"Vivir con integridad significa que siempre somos honestos y nos comportamos de forma coherente con estos valores. Con integridad, la vida es m\u00e1s f\u00e1cil.","breadcrumb":{"@id":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/#primaryimage","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2022\/05\/nathan-lemon-1-e1653232904122.jpg","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2022\/05\/nathan-lemon-1-e1653232904122.jpg","width":400,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/kimmelpsychology.com\/es\/vivir-con-integridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kimmelpsychology.com\/es\/kimmelhogar\/"},{"@type":"ListItem","position":2,"name":"Vivir con integridad"}]},{"@type":"WebSite","@id":"https:\/\/kimmelpsychology.com\/es\/#website","url":"https:\/\/kimmelpsychology.com\/es\/","name":"Kimmel Psychology","description":"Providing Psychological Services for Over 45 Years","publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimmelpsychology.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kimmelpsychology.com\/es\/#organization","name":"KimmelPsychology","url":"https:\/\/kimmelpsychology.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","width":682,"height":178,"caption":"KimmelPsychology"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/KimmelPsychology"]},{"@type":"Person","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a","name":"DrJoel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","caption":"DrJoel"},"sameAs":["https:\/\/kimmelpsychology.com","www. facebook.com\/Kimmelpsychology"]}]}},"_links":{"self":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/comments?post=9737"}],"version-history":[{"count":0,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media\/9363"}],"wp:attachment":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media?parent=9737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/categories?post=9737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/tags?post=9737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}