{"id":9747,"date":"2021-11-22T23:40:16","date_gmt":"2021-11-23T04:40:16","guid":{"rendered":"https:\/\/kimmelpsychology.com\/22-de-noviembre-de-2021-jfk\/"},"modified":"2021-11-22T23:40:16","modified_gmt":"2021-11-23T04:40:16","slug":"22-de-noviembre-de-2021-jfk","status":"publish","type":"post","link":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/","title":{"rendered":"22 de noviembre de 2021- JFK"},"content":{"rendered":"<p>Cuando empec\u00e9 a escribir este blog, me di cuenta de que fue hoy, hace 58 a\u00f1os, cuando el presidente de los Estados Unidos, John F. Kennedy, fue asesinado en Dallas Texas. Si no hubiera puesto fecha a este blog, no habr\u00eda pensado en ello. \u00bfY vosotros? \u00bfCu\u00e1ntos de vosotros record\u00e1is ese d\u00eda o lo aprendisteis en la escuela?   <\/p>\n<p>Recuerdo que volv\u00eda a casa del colegio y estaba en un autob\u00fas p\u00fablico cuando la gente empez\u00f3 a llorar. A\u00fan puedo imagin\u00e1rmelo y, durante las semanas siguientes, nuestro pa\u00eds estuvo traumatizado. Un presidente estadounidense tan prometedor asesinado en directo por televisi\u00f3n mientras iba en caravana. Qu\u00e9 impactante e incomprensible.   <\/p>\n<p>Muchas personas con las que he hablado recuerdan d\u00f3nde estaban y c\u00f3mo se enteraron en el momento del tiroteo. A\u00fan pueden visualizar d\u00f3nde estaban y lo que sintieron. Durante d\u00edas, estuvimos pegados al televisor para ver las noticias y el funeral.  <\/p>\n<p>Estados Unidos hab\u00eda sufrido uno de los peores traumas de su historia.<\/p>\n<p>A\u00fan quedan preguntas sobre qui\u00e9n fue el responsable y por qu\u00e9 ocurri\u00f3. No estoy seguro de que lleguemos a conocer nunca las respuestas a estas preguntas, aunque siguen existiendo preguntas conspirativas. <\/p>\n<p>Ahora que lo pienso, apenas se ha mencionado este suceso en las noticias de hoy. Quiz\u00e1 nos hayamos insensibilizado por los traumas de los atentados del 11 de septiembre, otros asesinatos y las m\u00faltiples guerras en las que ha luchado nuestro pa\u00eds. <\/p>\n<p>Tal vez nos hayamos vuelto demasiado insensibles o nos hayamos dividido pol\u00edticamente para recordar el pasado. Este es un acontecimiento que deber\u00eda recordarse y conmemorarse hoy. <\/p>\n<p>Como escribi\u00f3 George Santayana, el fil\u00f3sofo espa\u00f1ol, \u00abQuienes no pueden recordar el pasado est\u00e1n condenados a repetirlo\u00bb.<\/p>\n<p>\u00bfCu\u00e1ndo escucharemos?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando empec\u00e9 a escribir este blog, me di cuenta de que fue hoy, hace 58 a\u00f1os, cuando el presidente de los Estados Unidos, John F. Kennedy, fue asesinado en Dallas Texas. Si no hubiera puesto fecha a este blog, no habr\u00eda pensado en ello. \u00bfY vosotros? \u00bfCu\u00e1ntos de vosotros record\u00e1is ese d\u00eda o lo aprendisteis [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[158],"tags":[],"class_list":["post-9747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>22 de noviembre de 2021- JFK - Kimmel Psychology<\/title>\n<meta name=\"description\" content=\"Hoy es el 58 aniversario del asesinato del presidente John F. Kennedy. \u00bfHas o\u00eddo algo al respecto en las noticias de hoy?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"22 de noviembre de 2021- JFK - Kimmel Psychology\" \/>\n<meta property=\"og:description\" content=\"Hoy es el 58 aniversario del asesinato del presidente John F. Kennedy. \u00bfHas o\u00eddo algo al respecto en las noticias de hoy?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/\" \/>\n<meta property=\"og:site_name\" content=\"Kimmel Psychology\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/KimmelPsychology\" \/>\n<meta property=\"article:author\" content=\"www. facebook.com\/Kimmelpsychology\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-23T04:40:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/11\/John-Kennedy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"197\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DrJoel\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DrJoel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/\"},\"author\":{\"name\":\"DrJoel\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\"},\"headline\":\"22 de noviembre de 2021- JFK\",\"datePublished\":\"2021-11-23T04:40:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/\"},\"wordCount\":309,\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2021\\/11\\/John-Kennedy.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/\",\"name\":\"22 de noviembre de 2021- JFK - Kimmel Psychology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2021\\/11\\/John-Kennedy.jpg\",\"datePublished\":\"2021-11-23T04:40:16+00:00\",\"description\":\"Hoy es el 58 aniversario del asesinato del presidente John F. Kennedy. \u00bfHas o\u00eddo algo al respecto en las noticias de hoy?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/#primaryimage\",\"url\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2021\\/11\\/John-Kennedy.jpg\",\"contentUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2021\\/11\\/John-Kennedy.jpg\",\"width\":197,\"height\":256},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/22-de-noviembre-de-2021-jfk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/kimmelhogar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"22 de noviembre de 2021- JFK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"name\":\"Kimmel Psychology\",\"description\":\"Providing Psychological Services for Over 45 Years\",\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\",\"name\":\"KimmelPsychology\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"contentUrl\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"width\":682,\"height\":178,\"caption\":\"KimmelPsychology\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/KimmelPsychology\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\",\"name\":\"DrJoel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"caption\":\"DrJoel\"},\"sameAs\":[\"https:\\\/\\\/kimmelpsychology.com\",\"www. facebook.com\\\/Kimmelpsychology\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"22 de noviembre de 2021- JFK - Kimmel Psychology","description":"Hoy es el 58 aniversario del asesinato del presidente John F. Kennedy. \u00bfHas o\u00eddo algo al respecto en las noticias de hoy?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/","og_locale":"es_ES","og_type":"article","og_title":"22 de noviembre de 2021- JFK - Kimmel Psychology","og_description":"Hoy es el 58 aniversario del asesinato del presidente John F. Kennedy. \u00bfHas o\u00eddo algo al respecto en las noticias de hoy?","og_url":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/","og_site_name":"Kimmel Psychology","article_publisher":"http:\/\/www.facebook.com\/KimmelPsychology","article_author":"www. facebook.com\/Kimmelpsychology","article_published_time":"2021-11-23T04:40:16+00:00","og_image":[{"width":197,"height":256,"url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/11\/John-Kennedy.jpg","type":"image\/jpeg"}],"author":"DrJoel","twitter_misc":{"Escrito por":"DrJoel","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/#article","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/"},"author":{"name":"DrJoel","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a"},"headline":"22 de noviembre de 2021- JFK","datePublished":"2021-11-23T04:40:16+00:00","mainEntityOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/"},"wordCount":309,"publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/11\/John-Kennedy.jpg","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/","url":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/","name":"22 de noviembre de 2021- JFK - Kimmel Psychology","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/#primaryimage"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/11\/John-Kennedy.jpg","datePublished":"2021-11-23T04:40:16+00:00","description":"Hoy es el 58 aniversario del asesinato del presidente John F. Kennedy. \u00bfHas o\u00eddo algo al respecto en las noticias de hoy?","breadcrumb":{"@id":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/#primaryimage","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/11\/John-Kennedy.jpg","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/11\/John-Kennedy.jpg","width":197,"height":256},{"@type":"BreadcrumbList","@id":"https:\/\/kimmelpsychology.com\/es\/22-de-noviembre-de-2021-jfk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kimmelpsychology.com\/es\/kimmelhogar\/"},{"@type":"ListItem","position":2,"name":"22 de noviembre de 2021- JFK"}]},{"@type":"WebSite","@id":"https:\/\/kimmelpsychology.com\/es\/#website","url":"https:\/\/kimmelpsychology.com\/es\/","name":"Kimmel Psychology","description":"Providing Psychological Services for Over 45 Years","publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimmelpsychology.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kimmelpsychology.com\/es\/#organization","name":"KimmelPsychology","url":"https:\/\/kimmelpsychology.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","width":682,"height":178,"caption":"KimmelPsychology"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/KimmelPsychology"]},{"@type":"Person","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a","name":"DrJoel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","caption":"DrJoel"},"sameAs":["https:\/\/kimmelpsychology.com","www. facebook.com\/Kimmelpsychology"]}]}},"_links":{"self":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/comments?post=9747"}],"version-history":[{"count":0,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media\/9331"}],"wp:attachment":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media?parent=9747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/categories?post=9747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/tags?post=9747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}