{"id":9756,"date":"2021-03-17T13:51:10","date_gmt":"2021-03-17T17:51:10","guid":{"rendered":"https:\/\/kimmelpsychology.com\/puzzle-de-1000-piezas\/"},"modified":"2021-03-17T13:51:10","modified_gmt":"2021-03-17T17:51:10","slug":"puzzle-de-1000-piezas","status":"publish","type":"post","link":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/","title":{"rendered":"Puzzle de 1000 piezas"},"content":{"rendered":"<p>17 de marzo de 2021<\/p>\n<p>Hace varias semanas, empec\u00e9 a hacer un puzzle de 1000 piezas que compr\u00e9 en el Museo del Prado de Madrid hace varios a\u00f1os. Hac\u00eda bastantes a\u00f1os que no hac\u00eda un puzzle y decid\u00ed que ya era hora. Me gustaban los puzzles cuando era m\u00e1s joven, pero ahora me parecen m\u00e1s f\u00e1ciles que \u00e9ste.  <\/p>\n<p>El enigma es Las Meninas, un cuadro del siglo XVII de Diego Vel\u00e1zquez, bastante conocido entre los aficionados al arte. Su composici\u00f3n es muy compleja y enigm\u00e1tica, y plantea cuestiones sobre la realidad y la ilusi\u00f3n. Crea una relaci\u00f3n incierta entre las figuras representadas y el espectador. Yo no lo sab\u00eda y compr\u00e9 el puzzle porque me gustaba el cuadro.   <\/p>\n<p>Sin embargo, al emparejar las piezas del puzzle, me encontr\u00e9 con una experiencia \u00fanica. En cuanto al puzzle, experiment\u00e9 frustraci\u00f3n cuando las piezas no encajaban y disfrute cuando s\u00ed lo hac\u00edan. A veces ambos sentimientos al mismo tiempo. Tambi\u00e9n me estimul\u00f3 intelectualmente comprender lo que el artista represent\u00f3 en este cuadro, una de las obras maestras m\u00e1s estudiadas del arte. Vel\u00e1zquez utiliza espejos e invita al espectador a observar a los personajes mientras ellos miran al espectador; esto crea grandes ilusiones. Rara vez se sale de este cuadro sin una reacci\u00f3n emocional.     <\/p>\n<p>Cuando empec\u00e9, pens\u00e9 que s\u00f3lo iba a hacer un puzzle para pasar el tiempo durante la pandemia. En lugar de eso, descubr\u00ed una obra maestra de 460 a\u00f1os de antig\u00fcedad de un genial y revolucionario artista espa\u00f1ol. Te animo a que la busques en Internet.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>17 de marzo de 2021 Hace varias semanas, empec\u00e9 a hacer un puzzle de 1000 piezas que compr\u00e9 en el Museo del Prado de Madrid hace varios a\u00f1os. Hac\u00eda bastantes a\u00f1os que no hac\u00eda un puzzle y decid\u00ed que ya era hora. Me gustaban los puzzles cuando era m\u00e1s joven, pero ahora me parecen m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9259,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[158],"tags":[],"class_list":["post-9756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Puzzle de 1000 piezas - Kimmel Psychology<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puzzle de 1000 piezas - Kimmel Psychology\" \/>\n<meta property=\"og:description\" content=\"17 de marzo de 2021 Hace varias semanas, empec\u00e9 a hacer un puzzle de 1000 piezas que compr\u00e9 en el Museo del Prado de Madrid hace varios a\u00f1os. Hac\u00eda bastantes a\u00f1os que no hac\u00eda un puzzle y decid\u00ed que ya era hora. Me gustaban los puzzles cuando era m\u00e1s joven, pero ahora me parecen m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/\" \/>\n<meta property=\"og:site_name\" content=\"Kimmel Psychology\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/KimmelPsychology\" \/>\n<meta property=\"article:author\" content=\"www. facebook.com\/Kimmelpsychology\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-17T17:51:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/05\/DrKsBlogv2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DrJoel\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DrJoel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/\"},\"author\":{\"name\":\"DrJoel\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\"},\"headline\":\"Puzzle de 1000 piezas\",\"datePublished\":\"2021-03-17T17:51:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/\"},\"wordCount\":277,\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2021\\/05\\/DrKsBlogv2.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/\",\"name\":\"Puzzle de 1000 piezas - Kimmel Psychology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2021\\/05\\/DrKsBlogv2.jpg\",\"datePublished\":\"2021-03-17T17:51:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/#primaryimage\",\"url\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2021\\/05\\/DrKsBlogv2.jpg\",\"contentUrl\":\"https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2021\\/05\\/DrKsBlogv2.jpg\",\"width\":600,\"height\":399},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/puzzle-de-1000-piezas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/kimmelhogar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puzzle de 1000 piezas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"name\":\"Kimmel Psychology\",\"description\":\"Providing Psychological Services for Over 45 Years\",\"publisher\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#organization\",\"name\":\"KimmelPsychology\",\"url\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"contentUrl\":\"https:\\/\\/mlhtgnfxysf3.i.optimole.com\\/w:682\\/h:178\\/q:mauto\\/f:best\\/https:\\/\\/kimmelpsychology.com\\/wp-content\\/uploads\\/2014\\/01\\/Logo.png\",\"width\":682,\"height\":178,\"caption\":\"KimmelPsychology\"},\"image\":{\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/KimmelPsychology\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kimmelpsychology.com\\\/es\\\/#\\\/schema\\\/person\\\/81b43422d3c29b153bb449df4c42289a\",\"name\":\"DrJoel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g\",\"caption\":\"DrJoel\"},\"sameAs\":[\"https:\\\/\\\/kimmelpsychology.com\",\"www. facebook.com\\\/Kimmelpsychology\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puzzle de 1000 piezas - Kimmel Psychology","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/","og_locale":"es_ES","og_type":"article","og_title":"Puzzle de 1000 piezas - Kimmel Psychology","og_description":"17 de marzo de 2021 Hace varias semanas, empec\u00e9 a hacer un puzzle de 1000 piezas que compr\u00e9 en el Museo del Prado de Madrid hace varios a\u00f1os. Hac\u00eda bastantes a\u00f1os que no hac\u00eda un puzzle y decid\u00ed que ya era hora. Me gustaban los puzzles cuando era m\u00e1s joven, pero ahora me parecen m\u00e1s [&hellip;]","og_url":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/","og_site_name":"Kimmel Psychology","article_publisher":"http:\/\/www.facebook.com\/KimmelPsychology","article_author":"www. facebook.com\/Kimmelpsychology","article_published_time":"2021-03-17T17:51:10+00:00","og_image":[{"width":600,"height":399,"url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/05\/DrKsBlogv2.jpg","type":"image\/jpeg"}],"author":"DrJoel","twitter_misc":{"Escrito por":"DrJoel","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/#article","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/"},"author":{"name":"DrJoel","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a"},"headline":"Puzzle de 1000 piezas","datePublished":"2021-03-17T17:51:10+00:00","mainEntityOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/"},"wordCount":277,"publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/05\/DrKsBlogv2.jpg","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/","url":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/","name":"Puzzle de 1000 piezas - Kimmel Psychology","isPartOf":{"@id":"https:\/\/kimmelpsychology.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/#primaryimage"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/#primaryimage"},"thumbnailUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/05\/DrKsBlogv2.jpg","datePublished":"2021-03-17T17:51:10+00:00","breadcrumb":{"@id":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/#primaryimage","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/05\/DrKsBlogv2.jpg","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2021\/05\/DrKsBlogv2.jpg","width":600,"height":399},{"@type":"BreadcrumbList","@id":"https:\/\/kimmelpsychology.com\/es\/puzzle-de-1000-piezas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kimmelpsychology.com\/es\/kimmelhogar\/"},{"@type":"ListItem","position":2,"name":"Puzzle de 1000 piezas"}]},{"@type":"WebSite","@id":"https:\/\/kimmelpsychology.com\/es\/#website","url":"https:\/\/kimmelpsychology.com\/es\/","name":"Kimmel Psychology","description":"Providing Psychological Services for Over 45 Years","publisher":{"@id":"https:\/\/kimmelpsychology.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimmelpsychology.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kimmelpsychology.com\/es\/#organization","name":"KimmelPsychology","url":"https:\/\/kimmelpsychology.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","contentUrl":"https:\/\/mlhtgnfxysf3.i.optimole.com\/w:682\/h:178\/q:mauto\/f:best\/https:\/\/kimmelpsychology.com\/wp-content\/uploads\/2014\/01\/Logo.png","width":682,"height":178,"caption":"KimmelPsychology"},"image":{"@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/KimmelPsychology"]},{"@type":"Person","@id":"https:\/\/kimmelpsychology.com\/es\/#\/schema\/person\/81b43422d3c29b153bb449df4c42289a","name":"DrJoel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/829ee74ebe6aa950c36e28e64a3dc1974ba874d72000dab86241c6ca54f663bd?s=96&d=mm&r=g","caption":"DrJoel"},"sameAs":["https:\/\/kimmelpsychology.com","www. facebook.com\/Kimmelpsychology"]}]}},"_links":{"self":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/comments?post=9756"}],"version-history":[{"count":0,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/posts\/9756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media\/9259"}],"wp:attachment":[{"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/media?parent=9756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/categories?post=9756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kimmelpsychology.com\/es\/wp-json\/wp\/v2\/tags?post=9756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}